{"id":20153,"date":"2026-07-09T15:03:08","date_gmt":"2026-07-09T19:03:08","guid":{"rendered":"https:\/\/innovativemedicines.ca\/?page_id=20153"},"modified":"2026-07-13T14:45:49","modified_gmt":"2026-07-13T18:45:49","slug":"reclamations-et-transparence","status":"publish","type":"page","link":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/","title":{"rendered":"R\u00e9clamations et transparence"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light has-custom-content-position is-position-bottom-left hero tall\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim has-background-gradient\" style=\"background-color:#91999f;background:linear-gradient(360deg,#000000CB 0%,#00000033 100%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"1320\" src=\"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg\" class=\"wp-block-cover__image-background wp-post-image\" alt=\"\" data-object-fit=\"cover\" data-object-position=\"50% 38%\" style=\"object-position:50% 38%;\" srcset=\"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg 1980w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-300x200.jpg 300w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-1024x683.jpg 1024w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-768x512.jpg 768w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-1536x1024.jpg 1536w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-2048x1366.jpg 2048w, https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-744x496.jpg 744w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<span class=\"breadcrumbs\">\n            <span class=\"eyebrow crumb\"><a href=\"https:\/\/innovativemedicines.ca\/fr\/ethique\/\">\u00c9thique<\/a><\/span>\n    <\/span>\n\n\n<h1 class=\"wp-block-post-title has-text-color has-white-color\">R\u00e9clamations et transparence<\/h1>\n\n\n<p class=\"h4 has-white-color has-text-color\">La responsabilit\u00e9 n&rsquo;est pas seulement un principe, c&rsquo;est aussi une pratique. Nous rendons compte publiquement des violations du Code et mettons en \u0153uvre un processus transparent de traitement des plaintes, accessible \u00e0 tous les Canadiens.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Proc\u00e9dure de traitement des plaintes au sujet d\u2019une infraction au Code d\u2019\u00e9thique<\/h2>\n\n\n\n<h6 class=\"wp-block-heading\">LIGNES DIRECTRICES DU CEPI POUR LA R\u00c9CEPTION ET LE R\u00c8GLEMENT DES PLAINTES AU SUJET D\u2019UNE INFRACTION AU CODE D\u2019\u00c9THIQUE DE MNC<\/h6>\n\n\n\n<div class=\"wp-block-group low-margin\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-baytek-tabs has-white-background-color has-background wp-block-tabs has-vertical-orientation\"><div class=\"wp-block-tabs__inner-container\"><div class=\"wp-block-tabs__tab-labels\"><a class=\"tab-label active\" role=\"tab\" data-target=\"0\"><span>1. Coordonn\u00e9es<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"1\"><span>2. Objet de la plainte<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"2\"><span>3. Identit\u00e9 et coordonn\u00e9es des plaignants<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"3\"><span>4. Renseignements sur la plainte<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"4\"><span>5. R\u00e9f\u00e9rence au Code d\u2019\u00e9thique<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"5\"><span>6. \u00c9change de renseignements<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"6\"><span>7. Demandes de suivi<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"7\"><span>8. Plaintes concernant la publicit\u00e9<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"8\"><span>9. Langue des plaintes<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"9\"><span>10. D\u00e9lais<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"10\"><span>11. Bonne foi<\/span><\/a><a class=\"tab-label\" role=\"tab\" data-target=\"11\"><span>12. Transparence<\/span><\/a><\/div><div class=\"wp-block-tabs__tab-panels\">\n<div class=\"wp-block-tab\">\n<p>Les plaintes doivent \u00eatre soumises par \u00e9crit et envoy\u00e9es \u00e0 M\u00e9dicaments novateurs Canada (MNC) par la poste ou par courriel aux adresses ci-dessous \u00e0 des fins de suivi. Elles seront rejet\u00e9es si elles sont soumises verbalement, par t\u00e9l\u00e9phone ou par t\u00e9l\u00e9copieur. Toutes les plaintes doivent \u00eatre adress\u00e9es de la mani\u00e8re suivante.<\/p>\n\n\n\n<p>\u00c0 l\u2019attention du Comit\u00e9 d\u2019examen des pratiques de l\u2019industrie a\/s de la Directrice Ex\u00e9cutive, \u00c9thique et Affaires juridiques et r\u00e9glementaires, M\u00e9dicaments novateurs Canada, 310-99 rue Bank St., Ottawa, ON K1P 6B9 Les plaintes peuvent aussi \u00eatre envoy\u00e9es \u00e0 l\u2019adresse courriel <a href=\"mailto:plainte@imc-mnc.ca\" target=\"_blank\" rel=\"noreferrer noopener\">complaint@imc-mnc.ca<\/a>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaintes doivent pr\u00e9ciser la compagnie membre de MNC contre laquelle elles sont d\u00e9pos\u00e9es. Les plaignants sont inform\u00e9s que le Code d\u2019\u00e9thique s\u2019applique aux membres de MNC, et non aux fabricants de m\u00e9dicaments g\u00e9n\u00e9riques ni aux compagnies pharmaceutiques novatrices qui ne sont pas membres. Une liste des compagnies membres est accessible sur le site Web de M\u00e9dicaments novateurs Canada : <a href=\"https:\/\/innovativemedicines.ca\/fr\/a-propos\/#member-companies.\">https:\/\/innovativemedicines.ca\/fr\/a-propos\/#member-companies.<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaignants doivent s\u2019identifier et mentionner toute entreprise, organisation ou association \u00e0 laquelle ils sont affili\u00e9s. Ils doivent aussi fournir leurs coordonn\u00e9es et une adresse de retour compl\u00e8te. Les plaintes anonymes ou celles qui ne s\u2019accompagnent pas des coordonn\u00e9es requises seront rejet\u00e9es. \u00c0 moins que le plaignant ne s\u2019identifie lui-m\u00eame \u00e0 la compagnie membre faisant l\u2019objet de la plainte, MNC ne communiquera pas son identit\u00e9 \u00e0 la compagnie membre au cours du processus d\u2019enqu\u00eate et de r\u00e8glement de la plainte. Les compagnies membres qui sont elles-m\u00eames des plaignantes sont invit\u00e9es \u00e0 s\u2019identifier. Toutefois, les plaignants sont inform\u00e9s qu\u2019en cas d\u2019appel d\u2019une d\u00e9cision du Comit\u00e9 d\u2019examen des pratiques de l\u2019industrie (CEPI) concernant une plainte relative au Code (soit par le plaignant, soit par la compagnie membre, et \u00e0 moins que le plaignant ne choisisse d\u2019abandonner la plainte \u00e0 la suite de l\u2019appel de la compagnie membre), l\u2019identit\u00e9 du plaignant sera divulgu\u00e9e, et il sera tenu de participer \u00e0 l\u2019arbitrage..<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaignants doivent fournir par \u00e9crit le plus de renseignements pr\u00e9cis possible sur leur plainte, notamment la personne vis\u00e9e, l\u2019objet de la plainte, le moment de l\u2019\u00e9v\u00e9nement et l\u2019endroit o\u00f9 il s\u2019est produit. Les preuves soumises sous forme de documentation ou de photographies sont autoris\u00e9es, mais les plaignants sont inform\u00e9s que MNC ne les leur retournera pas n\u00e9cessairement. Ils sont aussi inform\u00e9s que le fait de fournir des renseignements clairs et pr\u00e9cis en temps utile facilite grandement le traitement de la plainte. Le CEPI ne prendra pas en consid\u00e9ration les plaintes concernant des infractions potentielles au Code qui ont \u00e9t\u00e9 soumises plus de cent vingt (120) jours apr\u00e8s la date o\u00f9 le plaignant a pris connaissance, ou aurait normalement d\u00fb prendre connaissance, du ou des \u00e9v\u00e9nements ayant donn\u00e9 lieu \u00e0 la plainte.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Dans la mesure du possible, les plaignants doivent indiquer le ou les articles du Code d\u2019\u00e9thique qui, \u00e0 leur avis, ont fait l\u2019objet d\u2019une infraction. Les r\u00e9f\u00e9rences au Code facilitent le traitement des plaintes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Avant que le CEPI ne proc\u00e8de \u00e0 l\u2019examen formel et sans pr\u00e9judice de la plainte, MNC tentera d\u2019amener les parties au litige \u00e0 proc\u00e9der \u00e0 un \u00e9change de renseignements. Cette d\u00e9marche consiste normalement, pour MNC, \u00e0 demander \u00e0 la compagnie membre qui fait l\u2019objet de la plainte de r\u00e9pondre rapidement par \u00e9crit \u00e0 cette derni\u00e8re. Si la compagnie membre est d\u2019accord, cette r\u00e9ponse sera communiqu\u00e9e au plaignant. Si le plaignant exprime sa volont\u00e9 de retirer sa plainte, le processus prendra fin. MNC fera alors parvenir une lettre informant les deux parties que le dossier est clos. Dans le cas contraire, MNC soumettra le dossier au CEPI afin qu\u2019il soit examin\u00e9.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaignants doivent \u00e9galement savoir que pour traiter et r\u00e9gler la plainte, MNC peut devoir envoyer des demandes de suivi. L\u2019absence de r\u00e9ponse \u00e0 ces demandes peut interrompre le processus de r\u00e8glement de la plainte.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaintes concernant la publicit\u00e9 diffus\u00e9e par des compagnies membres ne doivent pas \u00eatre soumises \u00e0 MNC, mais plut\u00f4t au Conseil consultatif de publicit\u00e9 pharmaceutique (CCPP), \u00e0 l\u2019adresse suivante :<\/p>\n\n\n\n<p>Conseil consultatif de publicit\u00e9 pharmaceutique 1305, promenade Pickering, bureau 300 Pickering (Ontario) LIV 3P2<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Les plaignants peuvent formuler leur plainte en fran\u00e7ais ou en anglais tant qu\u2019elle respecte les exigences.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>Le Code d\u2019\u00e9thique \u00e9tablit diff\u00e9rents d\u00e9lais pour le traitement et le r\u00e8glement des plaintes. M\u00eame si le CEPI et le personnel de MNC s\u2019efforcent de respecter ces \u00e9ch\u00e9ances dans la mesure du possible, des questions de logistique et d\u2019autres engagements des membres b\u00e9n\u00e9voles peuvent emp\u00eacher la stricte observance. Afin de r\u00e9duire au minimum les risques de conflits d\u2019horaires entre les membres, le CEPI pr\u00e9voira au moins quatre (4) r\u00e9unions au cours de l\u2019ann\u00e9e. Le CEPI et le personnel de MNC s\u2019assureront que les \u00e9ventuels retards ne causent pas de tort indu aux parties concern\u00e9es par la plainte.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>MNC tient \u00e0 s\u2019assurer que toutes les plaintes soumises conform\u00e9ment \u00e0 ce processus l\u2019ont \u00e9t\u00e9 de bonne foi. MNC se r\u00e9serve donc le droit de rejeter les plaintes \u00e0 son endroit ou \u00e0 l\u2019endroit de ses compagnies membres qui sont jug\u00e9es frivoles, vexatoires, abusives, douteuses ou de mauvaise foi.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-tab\">\n<p>MNC encourage la transparence, particuli\u00e8rement en ce qui concerne le Code d\u2019\u00e9thique. \u00c0 cette fin, un relev\u00e9 des plaintes li\u00e9es au Code (indiquant le nombre de plaintes d\u00e9pos\u00e9es, retir\u00e9es, rejet\u00e9es ou r\u00e9gl\u00e9es) sera affich\u00e9 sur le site Web des membres. Les noms des membres ne seront rendus publics sur le site Web que si le CEPI d\u00e9termine qu\u2019une infraction a eu lieu.<\/p>\n\n\n\n<p><strong>REMARQUE :<\/strong> Les plaignants sont inform\u00e9s que MNC se r\u00e9serve le droit de rejeter toute plainte, sans pr\u00e9avis, qui ne respecte pas les exigences ci-dessus.<\/p>\n<\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9ch\u00e9anciers<\/h3>\n\n\n\n<p>Le Code \u00e9tablit diff\u00e9rents d\u00e9lais pour le traitement et le r\u00e8glement des plaintes. M\u00eame si le CEPI et notre personnel s\u2019efforcent de respecter ces \u00e9ch\u00e9ances dans la mesure du possible, des questions de logistique et d\u2019autres engagements des membres b\u00e9n\u00e9voles peuvent rendre la chose impossible. Afin de r\u00e9duire au minimum les risques de conflits d\u2019horaires entre les membres, le CEPI pr\u00e9voira au moins quatre r\u00e9unions au cours de l\u2019ann\u00e9e. Le CEPI et notre personnel s\u2019efforceront de s\u2019assurer que les \u00e9ventuels retards ne causent pas de tort indu aux parties concern\u00e9es par la plainte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Transparence<\/h3>\n\n\n\n<p>Nous encourageons la transparence, particuli\u00e8rement en ce qui concerne le Code d\u2019\u00e9thique. \u00c0 cette fin, un relev\u00e9 des plaintes li\u00e9es au Code (indiquant le nombre de plaintes d\u00e9pos\u00e9es, retir\u00e9es, rejet\u00e9es ou r\u00e9gl\u00e9es) sera affich\u00e9 sur le site Web des membres. Les noms des membres ne seront rendus publics que si le CEPI d\u00e9termine qu\u2019une infraction a eu lieu.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-light-grey-background-color has-background\" id=\"plaintes\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Plaintes<\/h2>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Plaintes relatives au Code en 2024<\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: La compagnie X a all\u00e9gu\u00e9 que le financement par la compagnie&nbsp;Y de webinaires organis\u00e9s par une organisation de patients contrevient \u00e0 de nombreux articles du Code d\u2019\u00e9thique de M\u00e9dicaments novateurs Canada (ci-apr\u00e8s appel\u00e9 le \u00ab&nbsp;Code&nbsp;\u00bb), y compris l\u2019annexe&nbsp;A, \u00ab&nbsp;Lignes directrices de M\u00e9dicaments novateurs Canada relatives \u00e0 la transparence du financement des intervenants&nbsp;\u00bb.&nbsp;<\/p>\n\n\n\n<p>En plus, la compagnie X a all\u00e9gu\u00e9 que certaines des autres activit\u00e9s d\u2019apprentissage (ci-apr\u00e8s appel\u00e9es les \u00ab&nbsp;AAA&nbsp;\u00bb) de la compagnie&nbsp;Y contreviennent au Code ainsi qu\u2019au <em>Document d\u2019orientation sur la distinction entre les activit\u00e9s publicitaires et les autres activit\u00e9s pour les produits de sant\u00e9 de Sant\u00e9&nbsp;Canada<\/em>.&nbsp;<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: ao\u00fbt&nbsp;2024<\/p>\n\n\n\n<p><a href=\"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2024\/12\/20241028_IPRC_Decision_Final.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Plaintes relatives au Code en 2018<\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;X a all\u00e9gu\u00e9 que les programmes de soutien aux patients de la compagnie&nbsp;Y enfreignent les articles&nbsp;1.1 (Principes directeurs), 14.1.1 (Programmes de soutien aux patients), 14.2.2 (Assurer l\u2019int\u00e9grit\u00e9 de l\u2019industrie) et 14.2.3 (Conflit d\u2019int\u00e9r\u00eats) du Code d\u2019\u00e9thique de M\u00e9dicaments novateurs Canada (le \u00ab&nbsp;Code&nbsp;\u00bb).<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 10&nbsp;janvier&nbsp;2018<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2019\/05\/20180110_IPRC_Decision_Final.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Plaintes relatives au Code en 2016<\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;A c. compagnie&nbsp;B<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;A a all\u00e9gu\u00e9 que les programmes de soutien aux patients de la compagnie&nbsp;B enfreignent les principes directeurs&nbsp;2, 3 et 8, ainsi que les articles&nbsp;2.1 (Protection des renseignements sur les patients), 14.1.1 (Programmes de soutien aux patients), 14.2.2 (Assurer l\u2019int\u00e9grit\u00e9 de l\u2019industrie) et 14.2.3 (Conflit d\u2019int\u00e9r\u00eats) du Code d\u2019\u00e9thique de M\u00e9dicaments novateurs Canada (le \u00ab&nbsp;Code&nbsp;\u00bb).<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;d\u00e9cembre&nbsp;2016<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2017\/01\/Code_Complaint_IPRC_Decision_CompanyA_vs_CompanyB_FINAL.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;C c. compagnie&nbsp;D<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;C a all\u00e9gu\u00e9 que les programmes de soutien aux patients de la compagnie&nbsp;D enfreignent les principes directeurs&nbsp;2, 3 et 8, ainsi que les articles&nbsp;2.1 (Protection des renseignements sur les patients), 14.1.1 (Programmes de soutien aux patients), 14.2.2 (Assurer l\u2019int\u00e9grit\u00e9 de l\u2019industrie) et 14.2.3 (Conflit d\u2019int\u00e9r\u00eats) du Code d\u2019\u00e9thique de M\u00e9dicaments novateurs Canada (le \u00ab&nbsp;Code&nbsp;\u00bb).<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;d\u00e9cembre&nbsp;2016<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2017\/01\/Code_Complaint_IPRC_Decision_CompanyC_vs_CompanyD_FINAL.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;X a all\u00e9gu\u00e9 que les programmes de soutien aux patients de la compagnie&nbsp;Y enfreignent les principes directeurs&nbsp;2, 3 et 8, ainsi que les articles&nbsp;2.1 (Protection des renseignements sur les patients), 14.1.1 (Programmes de soutien aux patients), 14.2.2 (Assurer l\u2019int\u00e9grit\u00e9 de l\u2019industrie) et 14.2.3 (Conflit d\u2019int\u00e9r\u00eats) du Code d\u2019\u00e9thique de M\u00e9dicaments novateurs Canada (le \u00ab&nbsp;Code&nbsp;\u00bb).<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;d\u00e9cembre&nbsp;2016<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2017\/01\/Code_Complaint_IPRC_Decision_CompanyX_vs_CompanyY_FINAL.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2015<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;X a all\u00e9gu\u00e9 que la compagnie&nbsp;Y avait incit\u00e9 les m\u00e9decins membres d\u2019une organisation d\u2019achats group\u00e9s en offrant des incitatifs inappropri\u00e9s dans le cadre de la signature d\u2019un contrat d\u2019achat, en violation du principe directeur&nbsp;8 et de l\u2019article&nbsp;12.2.4.<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 2&nbsp;avril&nbsp;2015<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2015\/06\/20150402_IPRC_Decision_Anonymized_final-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2014<\/strong><\/h3>\n\n\n\n<p>Il n\u2019y a pas eu de d\u00e9cisions du CEPI pour cette ann\u00e9e.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2013<\/strong><\/h3>\n\n\n\n<p>Il n\u2019y a pas eu de d\u00e9cisions du CEPI pour cette ann\u00e9e.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2012<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Individu&nbsp;X, membre d\u2019un groupe de patients, c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: le plaignant a all\u00e9gu\u00e9 que la compagnie&nbsp;Y s\u2019\u00e9tait livr\u00e9e \u00e0 un marketing d\u00e9guis\u00e9 aupr\u00e8s de membres de groupes de patients en violation de l\u2019article&nbsp;12 (\u00c9tudes de march\u00e9) du Code d\u2019\u00e9thique.<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;mars&nbsp;2012<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2015\/06\/20120312_IPRC_Decision_Anonymized_FINAL-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2011<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Purdue Pharma c. Janssen<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: all\u00e9gation selon laquelle le programme de coupons de Janssen concernant<\/p>\n\n\n\n<p>Nucynta Cr et Jurnista (le \u00ab&nbsp;programme de coupons Janssen&nbsp;\u00bb) enfreint le principe directeur&nbsp;1 du Code d\u2019\u00e9thique de Rx&amp;D (le \u00ab&nbsp;Code&nbsp;\u00bb). Guid\u00e9 par la d\u00e9cision du Comit\u00e9 d\u2019appel (Purdue Pharma c. M.&nbsp;Ken Burns, pharmacien), le CEPI a d\u00e9termin\u00e9 que le programme de coupons Janssen contrevient au principe directeur&nbsp;1 du Code.<\/p>\n\n\n\n<p>Violation&nbsp;: principe directeur&nbsp;1<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;octobre&nbsp;2011<\/p>\n\n\n\n<p>Statut&nbsp;: infraction<\/p>\n\n\n\n<p><a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2015\/06\/20111020_IPRC_Decision_Purdue_vs_Janssen_FINAL.pdf\">D\u00e9cision du CEPI (en anglais seulement)<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X (non membre) c. compagnie&nbsp;Y inc.<\/strong><br \/><strong>Objet&nbsp;: produit&nbsp;Z (g\u00e9n\u00e9rique)<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: la compagnie&nbsp;Y a enfreint le Code d\u2019\u00e9thique dans le cadre de sa campagne (\u00e9tude&nbsp;123) pour donner la fausse impression aux professionnels de la sant\u00e9 canadiens que le produit g\u00e9n\u00e9rique&nbsp;Z est moins s\u00fbr, moins pur et moins efficace que le produit A.<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 20&nbsp;octobre&nbsp;2011<\/p>\n\n\n\n<p>Statut&nbsp;: <a href=\"http:\/\/innovativemedicines.ca\/wp-content\/uploads\/2015\/06\/20111020_IPRC_Decision_Anonymized_FINAL.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">aucune infraction<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Plaintes relatives au Code en 2010<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. compagnie&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>Plainte retir\u00e9e&nbsp;: la plainte devait \u00eatre entendue et jug\u00e9e par le CEPI. Toutefois, avant la r\u00e9union, Rx&amp;D a re\u00e7u une notification \u00e9crite de la compagnie&nbsp;Y stipulant qu\u2019elle retirait sa plainte. Par cons\u00e9quent, le CEPI n\u2019a pas discut\u00e9 de la question et Rx&amp;D a ferm\u00e9 le dossier.<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;:<\/p>\n\n\n\n<p>8&nbsp;septembre&nbsp;2010<\/p>\n\n\n\n<p>Statut&nbsp;: plainte retir\u00e9e<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Servier Canada Inc. c. M.&nbsp;Gabriel Baddour, pharmacien<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: all\u00e9gation selon laquelle un repr\u00e9sentant commercial de Servier aurait formul\u00e9 des commentaires inappropri\u00e9s concernant des probl\u00e8mes de s\u00e9curit\u00e9 potentiels associ\u00e9s \u00e0 la prescription d\u2019un concurrent g\u00e9n\u00e9rique. Le CEPI estime qu\u2019une ou plusieurs violations de l\u2019article&nbsp;8 (R\u00f4le du repr\u00e9sentant) ont \u00e9t\u00e9 commises.<\/p>\n\n\n\n<p>Violation&nbsp;: violations \u00e0 l\u2019article&nbsp;8<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;: 8&nbsp;septembre&nbsp;2010<\/p>\n\n\n\n<p>Statut&nbsp;: infraction<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-baytek-toggle\"><div class=\"toggle-header\"><p><strong><\/strong><strong>Compagnie&nbsp;X c. professionnel de la sant\u00e9&nbsp;Y<\/strong><\/p><\/div><div class=\"toggle-body\">\n<p>R\u00e9sum\u00e9&nbsp;: all\u00e9gation selon laquelle la compagnie&nbsp;X faisait la promotion d\u2019un m\u00e9dicament pour un usage qui n\u2019est pas mentionn\u00e9 dans la monographie de produit, ce qui contrevient \u00e0 un principe directeur du Code.<\/p>\n\n\n\n<p>Violation&nbsp;: aucune violation<\/p>\n\n\n\n<p>Appel&nbsp;: aucun appel<\/p>\n\n\n\n<p>Fin de l\u2019examen de la plainte&nbsp;:<\/p>\n\n\n\n<p>28&nbsp;avril&nbsp;2010<\/p>\n\n\n\n<p>Statut&nbsp;: aucune infraction<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Proc\u00e9dure de traitement des plaintes au sujet d\u2019une infraction au Code d\u2019\u00e9thique LIGNES DIRECTRICES DU CEPI POUR LA R\u00c9CEPTION ET [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20152,"parent":13863,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"9214,9220,9192,9194,9224,9212","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-20153","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9clamations et transparence - Innovative Medicines Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9clamations et transparence - Innovative Medicines Canada\" \/>\n<meta property=\"og:description\" content=\"Proc\u00e9dure de traitement des plaintes au sujet d\u2019une infraction au Code d\u2019\u00e9thique LIGNES DIRECTRICES DU CEPI POUR LA R\u00c9CEPTION ET [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Medicines Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T18:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/\",\"url\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/\",\"name\":\"R\u00e9clamations et transparence - Innovative Medicines Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/innovativemedicines.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg\",\"datePublished\":\"2026-07-09T19:03:08+00:00\",\"dateModified\":\"2026-07-13T18:45:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/innovativemedicines.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/innovativemedicines.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg\",\"width\":1980,\"height\":1320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/ethique\\\/reclamations-et-transparence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9thique\",\"item\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/a-propos\\\/ethique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9clamations et transparence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/\",\"name\":\"Innovative Medicines Canada\",\"description\":\"Transforming Canadians\u2019 lives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/innovativemedicines.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9clamations et transparence - Innovative Medicines Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9clamations et transparence - Innovative Medicines Canada","og_description":"Proc\u00e9dure de traitement des plaintes au sujet d\u2019une infraction au Code d\u2019\u00e9thique LIGNES DIRECTRICES DU CEPI POUR LA R\u00c9CEPTION ET [&hellip;]","og_url":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/","og_site_name":"Innovative Medicines Canada","article_modified_time":"2026-07-13T18:45:49+00:00","og_image":[{"width":1980,"height":1320,"url":"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/","url":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/","name":"R\u00e9clamations et transparence - Innovative Medicines Canada","isPartOf":{"@id":"https:\/\/innovativemedicines.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/#primaryimage"},"image":{"@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/#primaryimage"},"thumbnailUrl":"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg","datePublished":"2026-07-09T19:03:08+00:00","dateModified":"2026-07-13T18:45:49+00:00","breadcrumb":{"@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/#primaryimage","url":"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg","contentUrl":"https:\/\/innovativemedicines.ca\/wp-content\/uploads\/2026\/07\/21364ed5bd2fc828f74341e8561e93ed270d3f7c-scaled.jpg","width":1980,"height":1320},{"@type":"BreadcrumbList","@id":"https:\/\/innovativemedicines.ca\/fr\/ethique\/reclamations-et-transparence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/innovativemedicines.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9thique","item":"https:\/\/innovativemedicines.ca\/fr\/a-propos\/ethique\/"},{"@type":"ListItem","position":3,"name":"R\u00e9clamations et transparence"}]},{"@type":"WebSite","@id":"https:\/\/innovativemedicines.ca\/fr\/#website","url":"https:\/\/innovativemedicines.ca\/fr\/","name":"Innovative Medicines Canada","description":"Transforming Canadians\u2019 lives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/innovativemedicines.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/pages\/20153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/comments?post=20153"}],"version-history":[{"count":3,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/pages\/20153\/revisions"}],"predecessor-version":[{"id":20273,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/pages\/20153\/revisions\/20273"}],"up":[{"embeddable":true,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/pages\/13863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/media\/20152"}],"wp:attachment":[{"href":"https:\/\/innovativemedicines.ca\/fr\/wp-json\/wp\/v2\/media?parent=20153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}